{"id":4,"date":"2016-07-01T00:50:52","date_gmt":"2016-07-01T00:50:52","guid":{"rendered":"http:\/\/classiads.designinvento.net\/elementor\/classiads-shawk\/?page_id=4"},"modified":"2023-05-04T00:25:00","modified_gmt":"2023-05-04T00:25:00","slug":"listings","status":"publish","type":"page","link":"https:\/\/classiads.designinvento.net\/elementor\/classiads-ola\/listings\/","title":{"rendered":"Listings"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"4\" class=\"elementor elementor-4\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c48b844 elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c48b844\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c20871a\" data-id=\"c20871a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4b10ec4 elementor-widget elementor-widget-directorypress-main\" data-id=\"4b10ec4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"directorypress-main.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"directorypress-elementor-directorytype-widget\"><input type='hidden' name='el_archive_page'><div class=\"listings listing-archive listing-index archive-style-sidebar\"><div class=\"archive-content-wrapper clearfix\"><div class=\"listing-archive-sidearea clearfix\"><div class=\"main-search-bar\"><form action=\"https:\/\/classiads.designinvento.net\/elementor\/classiads-ola\/\" class=\"search-form-style1 directorypress-search-layout-vertical directorypress-content-wrap directorypress-search-form\" data-id=\"8316\" id=\"directorypress-search-form-8316\"><input type=\"hidden\" name=\"s\" value=\"search\" \/><input type=\"hidden\" name=\"hash\" value=\"364d8a9609cc614e952f48c42cb45b1c\" \/><input type=\"hidden\" name=\"handler\" value=\"directorypress_directory_handler\" \/><input type=\"hidden\" name=\"include_categories_children\" value=\"1\" \/><div class=\"directorypress-search-holder clearfix\"><div class=\"search-container clearfix\" style=\"margin-left:-0px; margin-right:-0px;\"><div class=\"default-search-fields-wrapper clearfix\"><div class=\"default-search-fields-section-label clearfix\"><label>filters<\/label><\/div><div class=\"default-search-fields-content-box clearfix\"><div class=\"keyword-search search-element-col pull-left directorypress-search-input-field-wrap\" style=\"width:100%; padding:0 0px;\"><div id=\"directorypress-tax-dropdowns-wrap-3456\" class=\"directorypress-tax-dropdowns-wrap\"><input type=\"hidden\" name=\"categories\" id=\"selected_tax[3456]\" class=\"selected_tax_directorypress-category\" value=\"0\" \/><input type=\"hidden\" name=\"categories_text\" id=\"selected_tax_text[3456]\" class=\"selected_tax_text_directorypress-category\" value=\"\" \/><select class=\"directorypress-form-control directorypress-selectmenu-directorypress-category\" data-icon=\"glyphicon glyphicon-search\" data-id=\"3456\" data-placeholder=\"Enter Keyword\" data-autocomplete-name=\"what_search\" data-autocomplete-value=\"\" data-ajax-search=1><option id=\"real-estate6a57832611235\" value=\"84\" data-level=\"1\" data-fonticolor=\"\" data-name=\"Real Estate\" data-sublabel=\"\"  data-icon=\"https:\/\/classiads.designinvento.net\/elementor\/classiads-ola\/wp-content\/uploads\/2025\/08\/5.png\" data-icontype=\"img\" data-count=\"9\">Real Estate<\/option><option id=\"vehicles6a57832611293\" value=\"70\" data-level=\"1\" data-fonticolor=\"\" data-name=\"Vehicles\" data-sublabel=\"\"  data-icon=\"https:\/\/classiads.designinvento.net\/elementor\/classiads-ola\/wp-content\/uploads\/2025\/08\/3.png\" data-icontype=\"img\" data-count=\"11\">Vehicles<\/option><option id=\"mobile-phones6a578326112dc\" value=\"254\" data-level=\"1\" data-fonticolor=\"\" data-name=\"Mobile Phones\" data-sublabel=\"\"  data-icon=\"https:\/\/classiads.designinvento.net\/elementor\/classiads-ola\/wp-content\/uploads\/2025\/08\/11.png\" data-icontype=\"img\" data-count=\"3\">Mobile Phones<\/option><option id=\"furniture6a57832611320\" value=\"256\" data-level=\"1\" data-fonticolor=\"\" data-name=\"Furniture\" data-sublabel=\"\"  data-icon=\"https:\/\/classiads.designinvento.net\/elementor\/classiads-ola\/wp-content\/uploads\/2025\/08\/16.png\" data-icontype=\"img\" data-count=\"7\">Furniture<\/option><option id=\"services6a57832611363\" value=\"113\" data-level=\"1\" data-fonticolor=\"\" data-name=\"Services\" data-sublabel=\"\"  data-icon=\"https:\/\/classiads.designinvento.net\/elementor\/classiads-ola\/wp-content\/uploads\/2025\/08\/14.png\" data-icontype=\"img\" data-count=\"6\">Services<\/option><option id=\"electronics6a578326113a5\" value=\"55\" data-level=\"1\" data-fonticolor=\"\" data-name=\"Electronics\" data-sublabel=\"\"  data-icon=\"https:\/\/classiads.designinvento.net\/elementor\/classiads-ola\/wp-content\/uploads\/2025\/08\/1.png\" data-icontype=\"img\" data-count=\"6\">Electronics<\/option><option id=\"jobs6a578326113f6\" value=\"112\" data-level=\"1\" data-fonticolor=\"\" data-name=\"Jobs\" data-sublabel=\"\"  data-icon=\"https:\/\/classiads.designinvento.net\/elementor\/classiads-ola\/wp-content\/uploads\/2025\/08\/7.png\" data-icontype=\"img\" data-count=\"4\">Jobs<\/option><option id=\"fashion6a57832611443\" value=\"77\" data-level=\"1\" data-fonticolor=\"\" data-name=\"Fashion\" data-sublabel=\"\"  data-icon=\"https:\/\/classiads.designinvento.net\/elementor\/classiads-ola\/wp-content\/uploads\/2025\/08\/13.png\" data-icontype=\"img\" data-count=\"5\">Fashion<\/option><option id=\"animal6a5783261146b\" value=\"114\" data-level=\"1\" data-fonticolor=\"\" data-name=\"Animal\" data-sublabel=\"\"  data-icon=\"https:\/\/classiads.designinvento.net\/elementor\/classiads-ola\/wp-content\/uploads\/2025\/08\/6.png\" data-icontype=\"img\" data-count=\"6\">Animal<\/option><option id=\"education6a5783261149f\" value=\"257\" data-level=\"1\" data-fonticolor=\"\" data-name=\"Education\" data-sublabel=\"\"  data-icon=\"https:\/\/classiads.designinvento.net\/elementor\/classiads-ola\/wp-content\/uploads\/2025\/08\/4.png\" data-icontype=\"img\" data-count=\"2\">Education<\/option><option id=\"baby-toys6a578326114c5\" value=\"255\" data-level=\"1\" data-fonticolor=\"\" data-name=\"Baby Toys\" data-sublabel=\"\"  data-icon=\"https:\/\/classiads.designinvento.net\/elementor\/classiads-ola\/wp-content\/uploads\/2025\/08\/10.png\" data-icontype=\"img\" data-count=\"1\">Baby Toys<\/option><option id=\"hotels-travel6a578326114ea\" value=\"62\" data-level=\"1\" data-fonticolor=\"\" data-name=\"Travel\" data-sublabel=\"\"  data-icon=\"https:\/\/classiads.designinvento.net\/elementor\/classiads-ola\/wp-content\/uploads\/2025\/08\/9.png\" data-icontype=\"img\" data-count=\"3\">Travel<\/option><option id=\"events-notices6a5783261151b\" value=\"91\" data-level=\"1\" data-fonticolor=\"\" data-name=\"Events\" data-sublabel=\"\"  data-icon=\"https:\/\/classiads.designinvento.net\/elementor\/classiads-ola\/wp-content\/uploads\/2025\/08\/8.png\" data-icontype=\"img\" data-count=\"1\">Events<\/option><option id=\"health-fitness6a5783261153e\" value=\"98\" data-level=\"1\" data-fonticolor=\"\" data-name=\"Health\" data-sublabel=\"\"  data-icon=\"https:\/\/classiads.designinvento.net\/elementor\/classiads-ola\/wp-content\/uploads\/2025\/08\/12.png\" data-icontype=\"img\" data-count=\"1\">Health<\/option><option id=\"matrimonial6a57832611562\" value=\"115\" data-level=\"1\" data-fonticolor=\"\" data-name=\"Matrimonial\" data-sublabel=\"\"  data-icon=\"https:\/\/classiads.designinvento.net\/elementor\/classiads-ola\/wp-content\/uploads\/2025\/08\/2.png\" data-icontype=\"img\" data-count=\"4\">Matrimonial<\/option><\/select><\/div><\/div><div class=\"search-element-col pull-left directorypress-search-input-field-wrap\" style=\"width:100%; padding:0 0px;\"><div id=\"directorypress-tax-dropdowns-wrap-669\" class=\"directorypress-tax-dropdowns-wrap\"><input type=\"hidden\" name=\"location_id\" id=\"selected_tax[669]\" class=\"selected_tax_directorypress-location\" value=\"0\" \/><input type=\"hidden\" name=\"location_id_text\" id=\"selected_tax_text[669]\" class=\"selected_tax_text_directorypress-location\" value=\"\" \/><select class=\"directorypress-form-control directorypress-selectmenu-directorypress-location\" data-icon=\"dicode-material-icons dicode-material-icons-map-marker-outline\" data-id=\"669\" data-placeholder=\"Enter Address\" data-autocomplete-name=\"address\" data-autocomplete-value=\"\"><option id=\"usa6a5783261276a\" value=\"2\" data-level=\"1\" data-fonticolor=\"\" data-name=\"USA\" data-sublabel=\"\"  data-icon=\"https:\/\/classiads.designinvento.net\/elementor\/classiads-ola\/wp-content\/plugins\/directorypress\/assets\/images\/marker.png\" data-icontype=\"img\" data-count=\"31\">USA<\/option><option id=\"canada6a57832612789\" value=\"194\" data-level=\"1\" data-fonticolor=\"\" data-name=\"canada\" data-sublabel=\"\"  data-icon=\"https:\/\/classiads.designinvento.net\/elementor\/classiads-ola\/wp-content\/plugins\/directorypress\/assets\/images\/marker.png\" data-icontype=\"img\" data-count=\"10\">canada<\/option><option id=\"china6a578326127a0\" value=\"195\" data-level=\"1\" data-fonticolor=\"\" data-name=\"china\" data-sublabel=\"\"  data-icon=\"https:\/\/classiads.designinvento.net\/elementor\/classiads-ola\/wp-content\/plugins\/directorypress\/assets\/images\/marker.png\" data-icontype=\"img\" data-count=\"0\">china<\/option><option id=\"united-kingdom6a578326127b4\" value=\"196\" data-level=\"1\" data-fonticolor=\"\" data-name=\"United Kingdom\" data-sublabel=\"\"  data-icon=\"https:\/\/classiads.designinvento.net\/elementor\/classiads-ola\/wp-content\/plugins\/directorypress\/assets\/images\/marker.png\" data-icontype=\"img\" data-count=\"11\">United Kingdom<\/option><option id=\"australia6a578326127c7\" value=\"202\" data-level=\"1\" data-fonticolor=\"\" data-name=\"Australia\" data-sublabel=\"\"  data-icon=\"https:\/\/classiads.designinvento.net\/elementor\/classiads-ola\/wp-content\/plugins\/directorypress\/assets\/images\/marker.png\" data-icontype=\"img\" data-count=\"1\">Australia<\/option><option id=\"pakistan6a578326127db\" value=\"203\" data-level=\"1\" data-fonticolor=\"\" data-name=\"Pakistan\" data-sublabel=\"\"  data-icon=\"https:\/\/classiads.designinvento.net\/elementor\/classiads-ola\/wp-content\/plugins\/directorypress\/assets\/images\/marker.png\" data-icontype=\"img\" data-count=\"4\">Pakistan<\/option><option id=\"india6a578326127ed\" value=\"204\" data-level=\"1\" data-fonticolor=\"\" data-name=\"India\" data-sublabel=\"\"  data-icon=\"https:\/\/classiads.designinvento.net\/elementor\/classiads-ola\/wp-content\/plugins\/directorypress\/assets\/images\/marker.png\" data-icontype=\"img\" data-count=\"2\">India<\/option><option id=\"france6a57832612800\" value=\"205\" data-level=\"1\" data-fonticolor=\"\" data-name=\"France\" data-sublabel=\"\"  data-icon=\"https:\/\/classiads.designinvento.net\/elementor\/classiads-ola\/wp-content\/plugins\/directorypress\/assets\/images\/marker.png\" data-icontype=\"img\" data-count=\"5\">France<\/option><option id=\"ksa6a57832612813\" value=\"206\" data-level=\"1\" data-fonticolor=\"\" data-name=\"KSA\" data-sublabel=\"\"  data-icon=\"https:\/\/classiads.designinvento.net\/elementor\/classiads-ola\/wp-content\/plugins\/directorypress\/assets\/images\/marker.png\" data-icontype=\"img\" data-count=\"0\">KSA<\/option><option id=\"italy6a57832612825\" value=\"207\" data-level=\"1\" data-fonticolor=\"\" data-name=\"Italy\" data-sublabel=\"\"  data-icon=\"https:\/\/classiads.designinvento.net\/elementor\/classiads-ola\/wp-content\/plugins\/directorypress\/assets\/images\/marker.png\" data-icontype=\"img\" data-count=\"1\">Italy<\/option><option id=\"new-zealand6a57832612837\" value=\"208\" data-level=\"1\" data-fonticolor=\"\" data-name=\"New Zealand\" data-sublabel=\"\"  data-icon=\"https:\/\/classiads.designinvento.net\/elementor\/classiads-ola\/wp-content\/plugins\/directorypress\/assets\/images\/marker.png\" data-icontype=\"img\" data-count=\"2\">New Zealand<\/option><option id=\"turkey6a5783261284a\" value=\"209\" data-level=\"1\" data-fonticolor=\"\" data-name=\"Turkey\" data-sublabel=\"\"  data-icon=\"https:\/\/classiads.designinvento.net\/elementor\/classiads-ola\/wp-content\/plugins\/directorypress\/assets\/images\/marker.png\" data-icontype=\"img\" data-count=\"2\">Turkey<\/option><\/select><\/div><\/div><div class=\"cz-areaalider search-element-col pull-left\" style=\"width:100%; padding:0 0px;\"><div class=\"form-group directorypress-jquery-ui-slider\"><div class=\"directorypress-distance-slider\"><div class=\"distance-slider\" id=\"radius_slider_8316\" data-id=\"8316\" title=\"0\"><\/div><input type=\"hidden\" name=\"radius\" id=\"radius_8316\" value=\"0\" \/><\/div><\/div><\/div><\/div><\/div>\r\n\t\t<script>\r\n\t\t\t(function($) {\r\n\t\t\t\t\"use strict\";\r\n\t\t\t\t\r\n\t\t\t\t$(function() {\r\n\t\t\t\t\tvar fields_in_categories = new Array();\r\n\t\t\t\t\t\t\t\tfields_in_categories[88] = [];\r\n\t\t\t\t\t\t\t\t\t\t\tfields_in_categories[18] = [];\r\n\t\t\t\t\t\t\t\t\t\t\tfields_in_categories[89] = [];\r\n\t\t\t\t\t\t\t\t\t\t\tfields_in_categories[9] = [];\r\n\t\t\t\t\t\t\t\t\t\t\tfields_in_categories[11] = [];\r\n\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t$(document).on(\"change\", \".selected_tax_directorypress-category\", function() {\r\n\t\t\t\t\t\thideShowFields($(this).val());\r\n\t\t\t\t\t});\r\n\t\t\t\r\n\t\t\t\t\tif ($(\".selected_tax_directorypress-category\").length > 0) {\r\n\t\t\t\t\t\thideShowFields($(\".selected_tax_directorypress-category\").val());\r\n\t\t\t\t\t} else {\r\n\t\t\t\t\t\thideShowFields(0);\r\n\t\t\t\t\t}\r\n\t\t\t\r\n\t\t\t\t\tfunction hideShowFields(id) {\r\n\t\t\t\t\t\tvar selected_categories_ids = [id];\r\n\t\t\t\r\n\t\t\t\t\t\t$(\".field-form-id-8316\").hide();\r\n\t\t\t\t\t\t$.each(fields_in_categories, function(index, value) {\r\n\t\t\t\t\t\t\tvar show_field = false;\r\n\t\t\t\t\t\t\tif (value != undefined) {\r\n\t\t\t\t\t\t\t\tif (value.length > 0) {\r\n\t\t\t\t\t\t\t\t\tvar key;\r\n\t\t\t\t\t\t\t\t\tfor (key in value) {\r\n\t\t\t\t\t\t\t\t\t\tvar key2;\r\n\t\t\t\t\t\t\t\t\t\tfor (key2 in selected_categories_ids)\r\n\t\t\t\t\t\t\t\t\t\t\tif (value[key] == selected_categories_ids[key2])\r\n\t\t\t\t\t\t\t\t\t\t\t\tshow_field = true;\r\n\t\t\t\t\t\t\t\t\t}\r\n\t\t\t\t\t\t\t\t}\r\n\t\t\t\t\t\t\t\tif ((value.length == 0 || show_field) && $(\".unique-form-field-id-\"+index+\"_8316\").length)\r\n\t\t\t\t\t\t\t\t\t$(\".unique-form-field-id-\"+index+\"_8316\").show();\r\n\t\t\t\t\t\t\t}\r\n\t\t\t\t\t\t});\r\n\t\t\t\t\t}\r\n\t\t\t\t\t\t\/\/ hack to remove visibility off hidden fields on initial load\r\n\t\t\t\tsetTimeout(function(){\r\n\t\t\t        $('[class*=\"field-id-\"]').unwrap();\r\n\t\t\t\t},500);\r\n\t\t\t\t});\r\n\t\t\t   \r\n\t\t\t\t\r\n\t\t\t})(jQuery);\r\n\t\t<\/script>\r\n\r\n        <div id=\"temp-field-wrapper\" style=\"display:none;\">\r\n\t\t<div class=\"search-element-col field-id-88 field-form-id-8316 unique-form-field-id-88_8316 field-type-status pull-left clearfix\" style=\" width:100%; padding:0 0px;\"><div class=\"search-content-field-label\"><label>Status<\/label><\/div><div class=\"search-field-content-wrapper search-checkbox-wrapper\"><div class=\"search-checkbox\"><label><input type=\"checkbox\" name=\"field_status[]\" value=\"1\"  class=\"selectpicker\" \/><span class=\"checkbox-item-name\">For Sale<span class=\"field-item-count\">0<\/span><\/span><span class=\"search-checkbox-item\"><\/span><\/label><\/div><div class=\"search-checkbox\"><label><input type=\"checkbox\" name=\"field_status[]\" value=\"2\"  class=\"selectpicker\" \/><span class=\"checkbox-item-name\">For Rent<span class=\"field-item-count\">0<\/span><\/span><span class=\"search-checkbox-item\"><\/span><\/label><\/div><div class=\"search-checkbox\"><label><input type=\"checkbox\" name=\"field_status[]\" value=\"3\"  class=\"selectpicker\" \/><span class=\"checkbox-item-name\">Wanted<span class=\"field-item-count\">0<\/span><\/span><span class=\"search-checkbox-item\"><\/span><\/label><\/div><\/div><\/div><div class=\"search-element-col field-id-18 field-form-id-8316 unique-form-field-id-18_8316 field-type-select pull-left clearfix\" style=\" width:100%; padding:0 0px;\"><div class=\"search-content-field-label\"><label>Brand Name<\/label><\/div><div class=\"search-field-content-wrapper\"><select name=\"field_Brand_Name\" class=\"search-field-content-wrapper cs-select cs-skin-elastic directorypress-select2\" style=\"width: 100%;\"><option value=\"\" >- Select Brand Name -<\/option><option value=\"1\" >Apple<\/option><option value=\"2\" >Samsung<\/option><option value=\"3\" >Huawei<\/option><option value=\"4\" >Qmobile<\/option><option value=\"5\" >Nokia<\/option><option value=\"6\" >Sony<\/option><option value=\"7\" >LG<\/option><option value=\"8\" >HTC<\/option><option value=\"9\" >Oppo<\/option><option value=\"10\" >BlackBerry<\/option><option value=\"11\" >Sony Ericsson<\/option><\/select><\/div><\/div><div class=\"search-element-col field-id-89 field-form-id-8316 unique-form-field-id-89_8316 field-type-color pull-left clearfix\" style=\" width:100%; padding:0 0px;\"><div class=\"search-content-field-label\"><label>colors<\/label><\/div><div class=\"search-field-content-wrapper search-checkbox-wrapper\"><div class=\"search-checkbox\"><label><input type=\"checkbox\" name=\"field_colors[]\" value=\"1\"  class=\"selectpicker\" \/><span class=\"checkbox-item-name\">Black<span class=\"field-item-count\">10<\/span><\/span><span class=\"search-checkbox-item\" style=\" background:#000000;border-color:#000000;color:#fff;\"><\/span><\/label><\/div><div class=\"search-checkbox\"><label><input type=\"checkbox\" name=\"field_colors[]\" value=\"2\"  class=\"selectpicker\" \/><span class=\"checkbox-item-name\">Red<span class=\"field-item-count\">17<\/span><\/span><span class=\"search-checkbox-item\" style=\" background:#dd3333;border-color:#dd3333;color:#fff;\"><\/span><\/label><\/div><div class=\"search-checkbox\"><label><input type=\"checkbox\" name=\"field_colors[]\" value=\"3\"  class=\"selectpicker\" \/><span class=\"checkbox-item-name\">Blue<span class=\"field-item-count\">2<\/span><\/span><span class=\"search-checkbox-item\" style=\" background:#0000ff;border-color:#0000ff;color:#fff;\"><\/span><\/label><\/div><div class=\"search-checkbox\"><label><input type=\"checkbox\" name=\"field_colors[]\" value=\"4\"  class=\"selectpicker\" \/><span class=\"checkbox-item-name\">Brown<span class=\"field-item-count\">3<\/span><\/span><span class=\"search-checkbox-item\" style=\" background:#a52a2a;border-color:#a52a2a;color:#fff;\"><\/span><\/label><\/div><div class=\"search-checkbox\"><label><input type=\"checkbox\" name=\"field_colors[]\" value=\"5\"  class=\"selectpicker\" \/><span class=\"checkbox-item-name\">Green<span class=\"field-item-count\">5<\/span><\/span><span class=\"search-checkbox-item\" style=\" background:#3cb371;border-color:#3cb371;color:#fff;\"><\/span><\/label><\/div><div class=\"search-checkbox\"><label><input type=\"checkbox\" name=\"field_colors[]\" value=\"6\"  class=\"selectpicker\" \/><span class=\"checkbox-item-name\">White<span class=\"field-item-count\">0<\/span><\/span><span class=\"search-checkbox-item\" style=\" background:#ffffff;border-color:#ffffff;color:#fff;\"><\/span><\/label><\/div><div class=\"search-checkbox\"><label><input type=\"checkbox\" name=\"field_colors[]\" value=\"7\"  class=\"selectpicker\" \/><span class=\"checkbox-item-name\">Purple<span class=\"field-item-count\">0<\/span><\/span><span class=\"search-checkbox-item\" style=\" background:#8224e3;border-color:#8224e3;color:#fff;\"><\/span><\/label><\/div><div class=\"search-checkbox\"><label><input type=\"checkbox\" name=\"field_colors[]\" value=\"8\"  class=\"selectpicker\" \/><span class=\"checkbox-item-name\">Yellow<span class=\"field-item-count\">5<\/span><\/span><span class=\"search-checkbox-item\" style=\" background:#efcd21;border-color:#efcd21;color:#fff;\"><\/span><\/label><\/div><div class=\"search-checkbox\"><label><input type=\"checkbox\" name=\"field_colors[]\" value=\"9\"  class=\"selectpicker\" \/><span class=\"checkbox-item-name\">Gray<span class=\"field-item-count\">7<\/span><\/span><span class=\"search-checkbox-item\" style=\" background:#b5b5b5;border-color:#b5b5b5;color:#fff;\"><\/span><\/label><\/div><\/div><\/div><div class=\"czprice-slider search-element-col field-id-9 field-type-price field-form-id-8316 unique-form-field-id-9_8316 pull-left\" style=\" width:100%; padding:0 0px;\">\r\n\t\t\t<div class=\"search-content-field-label\">\r\n\t\t\t<label>\r\n\t\t\t\tPrice\t\t\t\t<span id=\"slider_label_9_8316\">\r\n\t\t\t\t\tmin - max\t\t\t\t<\/span>\r\n\t\t\t<\/label>\r\n\t\t<\/div>\r\n\t\t<script>\r\n\t\t(function($) {\r\n\t\t\t\"use strict\";\r\n\t\t\r\n\t\t\t$(function() {\r\n\t\t\t\t\t\t\t\t\t\t\t\tvar slider_params_9_8316 = ['min', 1018,2016,3014,4012,5010,6008,7006,8004,9002, 'max'];\r\n\t\t\t\tvar slider_min_9_8316 = 19;\r\n\t\t\t\tvar slider_max_9_8316 = 10001;\r\n\t\t\t\t\t\t\t\t$('#range_slider_9_8316').slider({\r\n\t\t\t\t\t\t\t\t\t\tmin: slider_min_9_8316,\r\n\t\t\t\t\tmax: slider_max_9_8316,\r\n\t\t\t\t\trange: true,\r\n\t\t\t\t\t\t\t\t\t\tvalues: [19, 10001],\r\n\t\t\t\t\t\t\t\t\t\tslide: function(event, ui) {\r\n\t\t\t\t\t\tif ((ui.values[0]) >= ui.values[1]) {\r\n\t\t\t\t            return false;\r\n\t\t\t\t        }\r\n\r\n\t\t\t\t\t\t\t\t\t\t\t\tvar pre_symbol_position = '$';\r\n\t\t\t\t\t\tvar post_symbol_position = '';\r\n\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t\tif (ui.values[0] == 19) {\r\n\t\t\t\t\t\t\tvar min = 'min';\r\n\t\t\t\t\t\t} else {\r\n\t\t\t\t\t\t\tvar min = ui.values[0];\r\n\t\t\t\t\t\t}\r\n\t\t\t\t\t\tif (ui.values[1] == 10001) {\r\n\t\t\t\t\t\t\tvar max = 'max';\r\n\t\t\t\t\t\t} else {\r\n\t\t\t\t\t\t\tvar max = ui.values[1];\r\n\t\t\t\t\t\t}\r\n\t\r\n\t\t\t\t\t\t$('#slider_label_9_8316').html(pre_symbol_position + min + post_symbol_position + ' - ' + pre_symbol_position + max + post_symbol_position);\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t},\r\n\t\t\t\t\tstop: function(event, ui) {\r\n\t\t\t\t\t\tif ((ui.values[0]) >= ui.values[1]) {\r\n\t\t\t\t            return false;\r\n\t\t\t\t        }\r\n\r\n\t\t\t\t\t\t\t\t\t\t\t\tif (ui.values[0] == 19) {\r\n\t\t\t\t\t\t\t$('#field_9_8316_min').val('');\r\n\t\t\t\t\t\t} else {\r\n\t\t\t\t\t\t\t$('#field_9_8316_min').val(ui.values[0]);\r\n\t\t\t\t\t\t}\r\n\t\t\t\t\t\tif (ui.values[1] == 10001) {\r\n\t\t\t\t\t\t\t$('#field_9_8316_max').val('').trigger(\"change\");\r\n\t\t\t\t\t\t} else {\r\n\t\t\t\t\t\t\t$('#field_9_8316_max').val(ui.values[1]).trigger(\"change\");\r\n\t\t\t\t\t\t}\r\n\t\t\t\t\t\t\t\t\t\t\t}\r\n\t\t\t\t}).each(function() {\r\n\t\t\t\t\t$.each(slider_params_9_8316, function(index, value) {\r\n\t\t\t\t\t\t\t\t\t\t\t\tvar position = 'left';\r\n\t\t\t\t\t\t\t\t\t\t\t\tif (index % odd_even_label == 0) {\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\tvar pre_symbol_position = '$';\r\n\t\t\t\t\t\t\tvar post_symbol_position = '';\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t}\r\n\t\t\t\t\t});\r\n\t\t\t\t});\r\n\t\t\t});\r\n\t\t})(jQuery);\r\n\t<\/script>\r\n\t<div class=\"search-field-content-wrapper directorypress-jquery-ui-slider\">\r\n\t\t<div id=\"range_slider_9_8316\"><\/div>\r\n\t\t<div id=\"range_slider_9_8316_scale\" class=\"directorypress-range-slider-scale\"><\/div>\r\n\t\t<input type=\"hidden\" id=\"field_9_8316_min\" name=\"field_price_min\" value=\"\" \/>\r\n\t\t<input type=\"hidden\" id=\"field_9_8316_max\" name=\"field_price_max\" value=\"\" \/>\r\n\t<\/div>\r\n<\/div><div class=\"search-element-col field-id-11 field-form-id-8316 unique-form-field-id-11_8316 field-type-checkbox pull-left clearfix\" style=\" width:100%; padding:0 0px;\"><div class=\"search-content-field-label\"><label>Payment Options<\/label><\/div><div class=\"search-field-content-wrapper search-checkbox-wrapper\"><div class=\"search-checkbox\"><label><input type=\"checkbox\" name=\"field_payment-optons[]\" value=\"1\"  class=\"selectpicker\" \/><span class=\"checkbox-item-name\">American Express<\/span><span class=\"search-checkbox-item\"><\/span><\/label><\/div><div class=\"search-checkbox\"><label><input type=\"checkbox\" name=\"field_payment-optons[]\" value=\"2\"  class=\"selectpicker\" \/><span class=\"checkbox-item-name\">Cash<\/span><span class=\"search-checkbox-item\"><\/span><\/label><\/div><div class=\"search-checkbox\"><label><input type=\"checkbox\" name=\"field_payment-optons[]\" value=\"3\"  class=\"selectpicker\" \/><span class=\"checkbox-item-name\">Cheque<\/span><span class=\"search-checkbox-item\"><\/span><\/label><\/div><div class=\"search-checkbox\"><label><input type=\"checkbox\" name=\"field_payment-optons[]\" value=\"4\"  class=\"selectpicker\" \/><span class=\"checkbox-item-name\">Discover<\/span><span class=\"search-checkbox-item\"><\/span><\/label><\/div><div class=\"search-checkbox\"><label><input type=\"checkbox\" name=\"field_payment-optons[]\" value=\"5\"  class=\"selectpicker\" \/><span class=\"checkbox-item-name\">Interact<\/span><span class=\"search-checkbox-item\"><\/span><\/label><\/div><div class=\"search-checkbox\"><label><input type=\"checkbox\" name=\"field_payment-optons[]\" value=\"6\"  class=\"selectpicker\" \/><span class=\"checkbox-item-name\">MasterCard<\/span><span class=\"search-checkbox-item\"><\/span><\/label><\/div><div class=\"search-checkbox\"><label><input type=\"checkbox\" name=\"field_payment-optons[]\" value=\"7\"  class=\"selectpicker\" \/><span class=\"checkbox-item-name\">Visa<\/span><span class=\"search-checkbox-item\"><\/span><\/label><\/div><div class=\"search-checkbox\"><label><input type=\"checkbox\" name=\"field_payment-optons[]\" value=\"8\"  class=\"selectpicker\" \/><span class=\"checkbox-item-name\">Gift Sertificate<\/span><span class=\"search-checkbox-item\"><\/span><\/label><\/div><\/div><\/div>\t    <\/div>\r\n<div class=\"search-element-col pull-right directorypress-search-submit-button-wrap\" style=\"width:100%; padding:0 0px; margin-top:0px;\"><div class=\"directorypress-search-form-button directorypress-on-row-button\"><button type=\"submit\" name=\"submit\" class=\"btn btn-primary\" data-handler-hash=\"364d8a9609cc614e952f48c42cb45b1c\">Search<\/button><\/div><\/div><div class=\"clear_float\"><\/div><\/div><\/div><div class=\"directorypress-search-section directorypress-search-form-bottom clearfix\"><\/div><\/form><\/div><\/div><div class=\"listing-archive-content clearfix\"><div class=\"listing-parent\" id=\"directorypress-handler-364d8a9609cc614e952f48c42cb45b1c\" data-handler-hash=\"364d8a9609cc614e952f48c42cb45b1c\"><script>\r\n\t\t\tdirectorypress_handler_args_array[\"364d8a9609cc614e952f48c42cb45b1c\"] = {\"handler\":\"directorypress_directory_handler\",\"base_url\":\"\",\"order_by\":\"post_date\",\"order\":\"DESC\",\"perpage\":9,\"directorytypes\":null,\"is_home\":false,\"paged\":1,\"custom_home\":0,\"onepage\":0,\"hide_paginator\":0,\"hide_count\":0,\"scroll\":0,\"hide_content\":0,\"hide_order\":0,\"show_views_switcher\":\"1\",\"listings_view_type\":\"grid\",\"listing_post_style\":\"14\",\"listings_view_grid_columns\":\"3\",\"masonry_layout\":\"1\",\"2col_responsive\":\"1\",\"scroller_nav_style\":2,\"owl_nav\":false,\"loop\":false,\"autoplay\":false,\"autoplay_speed\":1000,\"desktop_items\":1,\"tab_items\":1,\"mobile_items\":1,\"scrolling_paginator\":0};\t\r\n\t\t<\/script><div class=\"directorypress-container-fluid directorypress-listings-block directorypress-listings-grid  directorypress-listings-grid-3\"><div class=\"directorypress-listings-block-header switcher-panel-style-2 clearfix\"><div class=\"directorypress-found-listings\">Result Found<span class=\"badge text-bg-secondary\">69<\/span><\/div><div class=\"view_swither_panel_style2 directorypress-options-links clearfix\"><div class=\"directorypress-orderby-links btn-group\" role=\"group\"><select class=\"directorypress-sorting directorypress-select2\"><option class=\"\" value=\"?order_by=post_date\" data-handler-hash=\"364d8a9609cc614e952f48c42cb45b1c\" data-orderby=\"post_date\" data-order=\"DESC\" selected>Sort By Date<\/option><option class=\"\" value=\"?order_by=rand\" data-handler-hash=\"364d8a9609cc614e952f48c42cb45b1c\" data-orderby=\"rand\" data-order=\"DESC\" >Random<\/option><option class=\"\" value=\"?order_by=title&#038;order=ASC\" data-handler-hash=\"364d8a9609cc614e952f48c42cb45b1c\" data-orderby=\"title\" data-order=\"ASC\" >Title<\/option><option class=\"\" value=\"?order_by=price\" data-handler-hash=\"364d8a9609cc614e952f48c42cb45b1c\" data-orderby=\"price\" data-order=\"DESC\" >Price<\/option><\/select><\/div><div id=\"view-btn-364d8a9609cc614e952f48c42cb45b1c\" class=\"directorypress-views-links pull-right\"><div class=\"btn-group\" role=\"group\"><a class=\"directorypress-list-view-btn in-active\" href=\"javascript: void(0);\" title=\"List View\" data-handler-hash=\"364d8a9609cc614e952f48c42cb45b1c\"><span class=\"pacz-fic3-list-2\" aria-hidden=\"true\"><\/span><\/a><a class=\"directorypress-grid-view-btn active\" href=\"javascript: void(0);\" title=\"Grid View\" data-handler-hash=\"364d8a9609cc614e952f48c42cb45b1c\" data-columns=\"3\"><span class=\"pacz-fic3-3x3-grid\" aria-hidden=\"true\"><\/span><\/a><\/div><\/div><\/div><\/div><div id=\"listing-block-364d8a9609cc614e952f48c42cb45b1c\" class=\"directorypress-listings-block-content no-carousel  m-grid clearfix\" style=\"margin-left:-5px;margin-right: -5px;\" data-uniqid=\"364d8a9609cc614e952f48c42cb45b1c\" ><article id=\"post-11082\" class=\"row directorypress-listing clearfix  responsive-2col m-grid-item listing-post-style-14 listing-grid-item\" style=\"padding-left:5px;padding-right:5px; margin-bottom:10px;\"><div class=\"directorypress-listing-item-holder clearfix\"><figure class=\"directorypress-listing-figure\"><a class=\"listing-thumbnail\" href=\"https:\/\/classiads.designinvento.net\/elementor\/classiads-ola\/listings\/amazing-villa-for-sale\/\"><img fetchpriority=\"high\" decoding=\"async\" alt=\"Amazing Villa For Sale\" src=\"https:\/\/classiads.designinvento.net\/elementor\/classiads-ola\/wp-content\/uploads\/bfi_thumb\/1-1-rj5lmyu5578opdn78y56ydlfk8z3n8fucwh9uchk30.jpg\" width=\"290\" height=\"190\" \/><\/a><div class=\"listing-grid-buttons clearfix\"><\/div><div class=\"listing-rating grid-rating\"><span class=\"rating-numbers\">5.0<\/span><span class=\"rating-stars\">\t<a href=\"#comments\" class=\"single-rating review_rate display-only\" data-dirrater=\"5.00\" itemprop=\"aggregateRating\" itemscope=\"\" itemtype=\"http:\/\/schema.org\/AggregateRating\">\r\n\t\t<span class=\"rating-value\">(<span itemprop=\"reviewCount\">1<\/span>)<\/span>\r\n\t\t<meta itemprop=\"ratingValue\" content = \"5.00\">\r\n\t<\/a>\r\n\t<\/span><\/div><\/figure><div class=\"clearfix directorypress-listing-text-content-wrap\"><div class=\"listng-author-img\"><a href=\"https:\/\/classiads.designinvento.net\/elementor\/classiads-ola\/author\/designinvento\/?profile=true\"><img class='directorypress-user-avatar' src='https:\/\/classiads.designinvento.net\/elementor\/classiads-ola\/wp-content\/uploads\/bfi_thumb\/img-02-768x693-1-rj5lmyu2cc1ggk7wfitymi37k7qk030vf9f7q2wx20.jpg' alt='author' \/><span class=\"author-in-active\"><\/span><\/a><\/div><div class=\"cat-wrapper\"><a class=\"listing-cat\" href=\"https:\/\/classiads.designinvento.net\/elementor\/classiads-ola\/listings\/business-category\/real-estate\/\" rel=\"tag\">Real Estate<\/a><\/div><header class=\"directorypress-listing-title\"><h2><a href=\"https:\/\/classiads.designinvento.net\/elementor\/classiads-ola\/listings\/amazing-villa-for-sale\/\" title=\"Amazing Villa For Sale\" rel=\"nofollow\">Amazing Villa For Sa<i class=\"user-verification-tag verified dicode-material-icons dicode-material-icons-checkbox-marked-circle\"><\/i><\/a><\/h2><\/header><div id=\"fields-block-inline11082\" class=\"grid-fields-wrapper inline-fields clearfix\" data-id=\"11082\"><\/div><div class=\"grid-fields-wrapper block-fields clearfix\"><\/div><div class=\"grid-exerpt-field clearfix\"><\/div><\/div><div class=\"listing-bottom-metas clearfix\"><div class=\"price\"><div class=\"directorypress-field-item directorypress-field-id-9 directorypress-field-type-price\">\r\n\t<span class=\"field-label\">\r\n\t\t\t<\/span>\r\n\t<span class=\"field-content symbol-left\">\r\n\t<span class=\"currency-symbol\">$<\/span>50000 <span class=\"price-options\">Fixed<\/span>\t<\/span>\r\n<\/div><\/div><div class=\"listing-ratting-icon-fields clearfix\"><div class=\"tooltip_fields clearfix\"><a id=\"11082\" href=\"void(0);\" class=\"add_to_favourites btn\" data-listingid=\"11082\" data-bs-toggle=\"tooltip\" title=\"Bookmark\" data-in_favourites_icon=\"dicode-material-icons dicode-material-icons-heart\" data-not_in_favourites_icon=\"dicode-material-icons dicode-material-icons-heart\"><span class=\"favourite-icon style2 unchecked dicode-material-icons dicode-material-icons-heart\"><\/span><\/a><div id=\"fields-block-inline-tooltip11082\" class=\"inline-tooltip-fields clearfix\" data-id=\"11082\"><div id=\"directorypress-6\" class=\"directorypress-field-item directorypress-field-type-text\">\r\n\t<span class=\"field-label inline-field-label\">\r\n\t\t\t<span class=\"directorypress-field-icon pacz-fic2-iphone\" data-bs-toggle=\"tooltip\" title=\"+&#57;&#50;&#51;45&#54;&#55;&#56;99\" data-placement=\"auto\"><\/span>\t<\/span>\r\n\t\t\t\t<\/div>\r\n<\/div><\/div><\/div><\/div><\/div><\/article><article id=\"post-11081\" class=\"row directorypress-listing clearfix  responsive-2col m-grid-item listing-post-style-14 listing-grid-item\" style=\"padding-left:5px;padding-right:5px; margin-bottom:10px;\"><div class=\"directorypress-listing-item-holder clearfix\"><figure class=\"directorypress-listing-figure\"><a class=\"listing-thumbnail\" href=\"https:\/\/classiads.designinvento.net\/elementor\/classiads-ola\/listings\/red-classic-car\/\"><img decoding=\"async\" alt=\"Red Classic Car\" src=\"https:\/\/classiads.designinvento.net\/elementor\/classiads-ola\/wp-content\/uploads\/bfi_thumb\/11-1-rj5lmyu5578opdn78y56ydlfk8z3n8fucwh9uchk30.jpg\" width=\"290\" height=\"190\" \/><\/a><div class=\"listing-grid-buttons clearfix\"><\/div><div class=\"listing-rating grid-rating\"><span class=\"rating-numbers\">5.0<\/span><span class=\"rating-stars\">\t<a href=\"#comments\" class=\"single-rating review_rate display-only\" data-dirrater=\"5.00\" itemprop=\"aggregateRating\" itemscope=\"\" itemtype=\"http:\/\/schema.org\/AggregateRating\">\r\n\t\t<span class=\"rating-value\">(<span itemprop=\"reviewCount\">1<\/span>)<\/span>\r\n\t\t<meta itemprop=\"ratingValue\" content = \"5.00\">\r\n\t<\/a>\r\n\t<\/span><\/div><\/figure><div class=\"clearfix directorypress-listing-text-content-wrap\"><div class=\"listng-author-img\"><a href=\"https:\/\/classiads.designinvento.net\/elementor\/classiads-ola\/author\/designinvento\/?profile=true\"><img class='directorypress-user-avatar' src='https:\/\/classiads.designinvento.net\/elementor\/classiads-ola\/wp-content\/uploads\/bfi_thumb\/img-02-768x693-1-rj5lmyu2cc1ggk7wfitymi37k7qk030vf9f7q2wx20.jpg' alt='author' \/><span class=\"author-in-active\"><\/span><\/a><\/div><div class=\"cat-wrapper\"><a class=\"listing-cat\" href=\"https:\/\/classiads.designinvento.net\/elementor\/classiads-ola\/listings\/business-category\/vehicles\/\" rel=\"tag\">Vehicles<\/a><span class=\"cat-seperator fas fa-angle-right\"><\/span><a class=\"listing-cat\" href=\"https:\/\/classiads.designinvento.net\/elementor\/classiads-ola\/listings\/business-category\/vehicles\/classic-modern\/\" rel=\"tag\">Classic Cars<\/a><\/div><header class=\"directorypress-listing-title\"><h2><a href=\"https:\/\/classiads.designinvento.net\/elementor\/classiads-ola\/listings\/red-classic-car\/\" title=\"Red Classic Car\" rel=\"nofollow\">Red Classic Car<i class=\"user-verification-tag verified dicode-material-icons dicode-material-icons-checkbox-marked-circle\"><\/i><\/a><\/h2><\/header><div id=\"fields-block-inline11081\" class=\"grid-fields-wrapper inline-fields clearfix\" data-id=\"11081\"><\/div><div class=\"grid-fields-wrapper block-fields clearfix\"><\/div><div class=\"grid-exerpt-field clearfix\"><\/div><\/div><div class=\"listing-bottom-metas clearfix\"><div class=\"price\"><div class=\"directorypress-field-item directorypress-field-id-9 directorypress-field-type-price\">\r\n\t<span class=\"field-label\">\r\n\t\t\t<\/span>\r\n\t<span class=\"field-content symbol-left\">\r\n\t<span class=\"currency-symbol\">$<\/span>80000 <span class=\"price-options\">Fixed<\/span>\t<\/span>\r\n<\/div><\/div><div class=\"listing-ratting-icon-fields clearfix\"><div class=\"tooltip_fields clearfix\"><a id=\"11081\" href=\"void(0);\" class=\"add_to_favourites btn\" data-listingid=\"11081\" data-bs-toggle=\"tooltip\" title=\"Bookmark\" data-in_favourites_icon=\"dicode-material-icons dicode-material-icons-heart\" data-not_in_favourites_icon=\"dicode-material-icons dicode-material-icons-heart\"><span class=\"favourite-icon style2 unchecked dicode-material-icons dicode-material-icons-heart\"><\/span><\/a><div id=\"fields-block-inline-tooltip11081\" class=\"inline-tooltip-fields clearfix\" data-id=\"11081\"><div id=\"directorypress-6\" class=\"directorypress-field-item directorypress-field-type-text\">\r\n\t<span class=\"field-label inline-field-label\">\r\n\t\t\t<span class=\"directorypress-field-icon pacz-fic2-iphone\" data-bs-toggle=\"tooltip\" title=\"&#43;&#57;&#50;&#51;&#52;&#53;67&#56;&#57;&#57;\" data-placement=\"auto\"><\/span>\t<\/span>\r\n\t\t\t\t<\/div>\r\n<\/div><\/div><\/div><\/div><\/div><\/article><article id=\"post-11080\" class=\"row directorypress-listing clearfix  responsive-2col m-grid-item listing-post-style-14 listing-grid-item\" style=\"padding-left:5px;padding-right:5px; margin-bottom:10px;\"><div class=\"directorypress-listing-item-holder clearfix\"><figure class=\"directorypress-listing-figure\"><a class=\"listing-thumbnail\" href=\"https:\/\/classiads.designinvento.net\/elementor\/classiads-ola\/listings\/iphone-14-pro-max\/\"><img decoding=\"async\" alt=\"Iphone 14 Pro Max\" src=\"https:\/\/classiads.designinvento.net\/elementor\/classiads-ola\/wp-content\/uploads\/bfi_thumb\/6-3-rj5lmyu5578opdn78y56ydlfk8z3n8fucwh9uchk30.jpg\" width=\"290\" height=\"190\" \/><\/a><div class=\"listing-grid-buttons clearfix\"><\/div><div class=\"listing-rating grid-rating\"><span class=\"rating-numbers\">5.0<\/span><span class=\"rating-stars\">\t<a href=\"#comments\" class=\"single-rating review_rate display-only\" data-dirrater=\"5.00\" itemprop=\"aggregateRating\" itemscope=\"\" itemtype=\"http:\/\/schema.org\/AggregateRating\">\r\n\t\t<span class=\"rating-value\">(<span itemprop=\"reviewCount\">1<\/span>)<\/span>\r\n\t\t<meta itemprop=\"ratingValue\" content = \"5.00\">\r\n\t<\/a>\r\n\t<\/span><\/div><\/figure><div class=\"clearfix directorypress-listing-text-content-wrap\"><div class=\"listng-author-img\"><a href=\"https:\/\/classiads.designinvento.net\/elementor\/classiads-ola\/author\/designinvento\/?profile=true\"><img class='directorypress-user-avatar' src='https:\/\/classiads.designinvento.net\/elementor\/classiads-ola\/wp-content\/uploads\/bfi_thumb\/img-02-768x693-1-rj5lmyu2cc1ggk7wfitymi37k7qk030vf9f7q2wx20.jpg' alt='author' \/><span class=\"author-in-active\"><\/span><\/a><\/div><div class=\"cat-wrapper\"><a class=\"listing-cat\" href=\"https:\/\/classiads.designinvento.net\/elementor\/classiads-ola\/listings\/business-category\/mobile-phones\/\" rel=\"tag\">Mobile Phones<\/a><span class=\"cat-seperator fas fa-angle-right\"><\/span><a class=\"listing-cat\" href=\"https:\/\/classiads.designinvento.net\/elementor\/classiads-ola\/listings\/business-category\/mobile-phones\/apple\/\" rel=\"tag\">Apple<\/a><\/div><header class=\"directorypress-listing-title\"><h2><a href=\"https:\/\/classiads.designinvento.net\/elementor\/classiads-ola\/listings\/iphone-14-pro-max\/\" title=\"Iphone 14 Pro Max\" rel=\"nofollow\">Iphone 14 Pro Max<i class=\"user-verification-tag verified dicode-material-icons dicode-material-icons-checkbox-marked-circle\"><\/i><\/a><\/h2><\/header><div id=\"fields-block-inline11080\" class=\"grid-fields-wrapper inline-fields clearfix\" data-id=\"11080\"><\/div><div class=\"grid-fields-wrapper block-fields clearfix\"><\/div><div class=\"grid-exerpt-field clearfix\"><\/div><\/div><div class=\"listing-bottom-metas clearfix\"><div class=\"price\"><div class=\"directorypress-field-item directorypress-field-id-9 directorypress-field-type-price\">\r\n\t<span class=\"field-label\">\r\n\t\t\t<\/span>\r\n\t<span class=\"field-content symbol-left\">\r\n\t<span class=\"currency-symbol\">$<\/span>950 <span class=\"price-options\">Fixed<\/span>\t<\/span>\r\n<\/div><\/div><div class=\"listing-ratting-icon-fields clearfix\"><div class=\"tooltip_fields clearfix\"><a id=\"11080\" href=\"void(0);\" class=\"add_to_favourites btn\" data-listingid=\"11080\" data-bs-toggle=\"tooltip\" title=\"Bookmark\" data-in_favourites_icon=\"dicode-material-icons dicode-material-icons-heart\" data-not_in_favourites_icon=\"dicode-material-icons dicode-material-icons-heart\"><span class=\"favourite-icon style2 unchecked dicode-material-icons dicode-material-icons-heart\"><\/span><\/a><div id=\"fields-block-inline-tooltip11080\" class=\"inline-tooltip-fields clearfix\" data-id=\"11080\"><div id=\"directorypress-6\" class=\"directorypress-field-item directorypress-field-type-text\">\r\n\t<span class=\"field-label inline-field-label\">\r\n\t\t\t<span class=\"directorypress-field-icon pacz-fic2-iphone\" data-bs-toggle=\"tooltip\" title=\"+&#57;&#50;345&#54;&#55;89&#57;\" data-placement=\"auto\"><\/span>\t<\/span>\r\n\t\t\t\t<\/div>\r\n<\/div><\/div><\/div><\/div><\/div><\/article><article id=\"post-11079\" class=\"row directorypress-listing clearfix  responsive-2col m-grid-item listing-post-style-14 listing-grid-item\" style=\"padding-left:5px;padding-right:5px; margin-bottom:10px;\"><div class=\"directorypress-listing-item-holder clearfix\"><figure class=\"directorypress-listing-figure\"><a class=\"listing-thumbnail\" href=\"https:\/\/classiads.designinvento.net\/elementor\/classiads-ola\/listings\/nike-fancy-shoes\/\"><img loading=\"lazy\" decoding=\"async\" alt=\"Nike Fancy Shoes\" src=\"https:\/\/classiads.designinvento.net\/elementor\/classiads-ola\/wp-content\/uploads\/bfi_thumb\/nike-rj5lmyu5578opdn78y56ydlfk8z3n8fucwh9uchk30.jpg\" width=\"290\" height=\"190\" \/><\/a><div class=\"listing-grid-buttons clearfix\"><\/div><div class=\"listing-rating grid-rating\"><span class=\"rating-numbers\">5.0<\/span><span class=\"rating-stars\">\t<a href=\"#comments\" class=\"single-rating review_rate display-only\" data-dirrater=\"5.00\" itemprop=\"aggregateRating\" itemscope=\"\" itemtype=\"http:\/\/schema.org\/AggregateRating\">\r\n\t\t<span class=\"rating-value\">(<span itemprop=\"reviewCount\">1<\/span>)<\/span>\r\n\t\t<meta itemprop=\"ratingValue\" content = \"5.00\">\r\n\t<\/a>\r\n\t<\/span><\/div><\/figure><div class=\"clearfix directorypress-listing-text-content-wrap\"><div class=\"listng-author-img\"><a href=\"https:\/\/classiads.designinvento.net\/elementor\/classiads-ola\/author\/designinvento\/?profile=true\"><img class='directorypress-user-avatar' src='https:\/\/classiads.designinvento.net\/elementor\/classiads-ola\/wp-content\/uploads\/bfi_thumb\/img-02-768x693-1-rj5lmyu2cc1ggk7wfitymi37k7qk030vf9f7q2wx20.jpg' alt='author' \/><span class=\"author-in-active\"><\/span><\/a><\/div><div class=\"cat-wrapper\"><a class=\"listing-cat\" href=\"https:\/\/classiads.designinvento.net\/elementor\/classiads-ola\/listings\/business-category\/fashion\/\" rel=\"tag\">Fashion<\/a><span class=\"cat-seperator fas fa-angle-right\"><\/span><a class=\"listing-cat\" href=\"https:\/\/classiads.designinvento.net\/elementor\/classiads-ola\/listings\/business-category\/fashion\/shoes-mf\/\" rel=\"tag\">Shoes<\/a><\/div><header class=\"directorypress-listing-title\"><h2><a href=\"https:\/\/classiads.designinvento.net\/elementor\/classiads-ola\/listings\/nike-fancy-shoes\/\" title=\"Nike Fancy Shoes\" rel=\"nofollow\">Nike Fancy Shoes<i class=\"user-verification-tag verified dicode-material-icons dicode-material-icons-checkbox-marked-circle\"><\/i><\/a><\/h2><\/header><div id=\"fields-block-inline11079\" class=\"grid-fields-wrapper inline-fields clearfix\" data-id=\"11079\"><\/div><div class=\"grid-fields-wrapper block-fields clearfix\"><\/div><div class=\"grid-exerpt-field clearfix\"><\/div><\/div><div class=\"listing-bottom-metas clearfix\"><div class=\"price\"><div class=\"directorypress-field-item directorypress-field-id-9 directorypress-field-type-price\">\r\n\t<span class=\"field-label\">\r\n\t\t\t<\/span>\r\n\t<span class=\"field-content symbol-left\">\r\n\t<span class=\"currency-symbol\">$<\/span>1500 <span class=\"price-options\">Fixed<\/span>\t<\/span>\r\n<\/div><\/div><div class=\"listing-ratting-icon-fields clearfix\"><div class=\"tooltip_fields clearfix\"><a id=\"11079\" href=\"void(0);\" class=\"add_to_favourites btn\" data-listingid=\"11079\" data-bs-toggle=\"tooltip\" title=\"Bookmark\" data-in_favourites_icon=\"dicode-material-icons dicode-material-icons-heart\" data-not_in_favourites_icon=\"dicode-material-icons dicode-material-icons-heart\"><span class=\"favourite-icon style2 unchecked dicode-material-icons dicode-material-icons-heart\"><\/span><\/a><div id=\"fields-block-inline-tooltip11079\" class=\"inline-tooltip-fields clearfix\" data-id=\"11079\"><div id=\"directorypress-6\" class=\"directorypress-field-item directorypress-field-type-text\">\r\n\t<span class=\"field-label inline-field-label\">\r\n\t\t\t<span class=\"directorypress-field-icon pacz-fic2-iphone\" data-bs-toggle=\"tooltip\" title=\"+&#57;&#50;&#51;&#52;56&#55;&#56;99\" data-placement=\"auto\"><\/span>\t<\/span>\r\n\t\t\t\t<\/div>\r\n<\/div><\/div><\/div><\/div><\/div><\/article><article id=\"post-11078\" class=\"row directorypress-listing clearfix  responsive-2col m-grid-item listing-post-style-14 listing-grid-item\" style=\"padding-left:5px;padding-right:5px; margin-bottom:10px;\"><div class=\"directorypress-listing-item-holder clearfix\"><figure class=\"directorypress-listing-figure\"><a class=\"listing-thumbnail\" href=\"https:\/\/classiads.designinvento.net\/elementor\/classiads-ola\/listings\/best-4k-drone\/\"><img loading=\"lazy\" decoding=\"async\" alt=\"Best 4K Drone\" src=\"https:\/\/classiads.designinvento.net\/elementor\/classiads-ola\/wp-content\/uploads\/bfi_thumb\/dron-rj5lmyu5578opdn78y56ydlfk8z3n8fucwh9uchk30.jpg\" width=\"290\" height=\"190\" \/><\/a><div class=\"listing-grid-buttons clearfix\"><\/div><div class=\"listing-rating grid-rating\"><span class=\"rating-numbers\">5.0<\/span><span class=\"rating-stars\">\t<a href=\"#comments\" class=\"single-rating review_rate display-only\" data-dirrater=\"5.00\" itemprop=\"aggregateRating\" itemscope=\"\" itemtype=\"http:\/\/schema.org\/AggregateRating\">\r\n\t\t<span class=\"rating-value\">(<span itemprop=\"reviewCount\">1<\/span>)<\/span>\r\n\t\t<meta itemprop=\"ratingValue\" content = \"5.00\">\r\n\t<\/a>\r\n\t<\/span><\/div><\/figure><div class=\"clearfix directorypress-listing-text-content-wrap\"><div class=\"listng-author-img\"><a href=\"https:\/\/classiads.designinvento.net\/elementor\/classiads-ola\/author\/designinvento\/?profile=true\"><img class='directorypress-user-avatar' src='https:\/\/classiads.designinvento.net\/elementor\/classiads-ola\/wp-content\/uploads\/bfi_thumb\/img-02-768x693-1-rj5lmyu2cc1ggk7wfitymi37k7qk030vf9f7q2wx20.jpg' alt='author' \/><span class=\"author-in-active\"><\/span><\/a><\/div><div class=\"cat-wrapper\"><a class=\"listing-cat\" href=\"https:\/\/classiads.designinvento.net\/elementor\/classiads-ola\/listings\/business-category\/electronics\/\" rel=\"tag\">Electronics<\/a><\/div><header class=\"directorypress-listing-title\"><h2><a href=\"https:\/\/classiads.designinvento.net\/elementor\/classiads-ola\/listings\/best-4k-drone\/\" title=\"Best 4K Drone\" rel=\"nofollow\">Best 4K Drone<i class=\"user-verification-tag verified dicode-material-icons dicode-material-icons-checkbox-marked-circle\"><\/i><\/a><\/h2><\/header><div id=\"fields-block-inline11078\" class=\"grid-fields-wrapper inline-fields clearfix\" data-id=\"11078\"><\/div><div class=\"grid-fields-wrapper block-fields clearfix\"><\/div><div class=\"grid-exerpt-field clearfix\"><\/div><\/div><div class=\"listing-bottom-metas clearfix\"><div class=\"price\"><div class=\"directorypress-field-item directorypress-field-id-9 directorypress-field-type-price\">\r\n\t<span class=\"field-label\">\r\n\t\t\t<\/span>\r\n\t<span class=\"field-content symbol-left\">\r\n\t<span class=\"currency-symbol\">$<\/span>3500 <span class=\"price-options\">Fixed<\/span>\t<\/span>\r\n<\/div><\/div><div class=\"listing-ratting-icon-fields clearfix\"><div class=\"tooltip_fields clearfix\"><a id=\"11078\" href=\"void(0);\" class=\"add_to_favourites btn\" data-listingid=\"11078\" data-bs-toggle=\"tooltip\" title=\"Bookmark\" data-in_favourites_icon=\"dicode-material-icons dicode-material-icons-heart\" data-not_in_favourites_icon=\"dicode-material-icons dicode-material-icons-heart\"><span class=\"favourite-icon style2 unchecked dicode-material-icons dicode-material-icons-heart\"><\/span><\/a><div id=\"fields-block-inline-tooltip11078\" class=\"inline-tooltip-fields clearfix\" data-id=\"11078\"><div id=\"directorypress-6\" class=\"directorypress-field-item directorypress-field-type-text\">\r\n\t<span class=\"field-label inline-field-label\">\r\n\t\t\t<span class=\"directorypress-field-icon pacz-fic2-iphone\" data-bs-toggle=\"tooltip\" title=\"&#43;&#57;&#50;3456&#55;&#56;&#57;&#57;\" data-placement=\"auto\"><\/span>\t<\/span>\r\n\t\t\t\t<\/div>\r\n<\/div><\/div><\/div><\/div><\/div><\/article><article id=\"post-11077\" class=\"row directorypress-listing clearfix  responsive-2col m-grid-item listing-post-style-14 listing-grid-item\" style=\"padding-left:5px;padding-right:5px; margin-bottom:10px;\"><div class=\"directorypress-listing-item-holder clearfix\"><figure class=\"directorypress-listing-figure\"><a class=\"listing-thumbnail\" href=\"https:\/\/classiads.designinvento.net\/elementor\/classiads-ola\/listings\/finding-best-match\/\"><img loading=\"lazy\" decoding=\"async\" alt=\"Finding Best Match\" src=\"https:\/\/classiads.designinvento.net\/elementor\/classiads-ola\/wp-content\/uploads\/bfi_thumb\/w1-rj5lmyu5578opdn78y56ydlfk8z3n8fucwh9uchk30.jpg\" width=\"290\" height=\"190\" \/><\/a><div class=\"listing-grid-buttons clearfix\"><\/div><div class=\"listing-rating grid-rating\"><span class=\"rating-numbers\">4.0<\/span><span class=\"rating-stars\">\t<a href=\"#comments\" class=\"single-rating review_rate display-only\" data-dirrater=\"4.00\" itemprop=\"aggregateRating\" itemscope=\"\" itemtype=\"http:\/\/schema.org\/AggregateRating\">\r\n\t\t<span class=\"rating-value\">(<span itemprop=\"reviewCount\">1<\/span>)<\/span>\r\n\t\t<meta itemprop=\"ratingValue\" content = \"4.00\">\r\n\t<\/a>\r\n\t<\/span><\/div><\/figure><div class=\"clearfix directorypress-listing-text-content-wrap\"><div class=\"listng-author-img\"><a href=\"https:\/\/classiads.designinvento.net\/elementor\/classiads-ola\/author\/designinvento\/?profile=true\"><img class='directorypress-user-avatar' src='https:\/\/classiads.designinvento.net\/elementor\/classiads-ola\/wp-content\/uploads\/bfi_thumb\/img-02-768x693-1-rj5lmyu2cc1ggk7wfitymi37k7qk030vf9f7q2wx20.jpg' alt='author' \/><span class=\"author-in-active\"><\/span><\/a><\/div><div class=\"cat-wrapper\"><a class=\"listing-cat\" href=\"https:\/\/classiads.designinvento.net\/elementor\/classiads-ola\/listings\/business-category\/matrimonial\/\" rel=\"tag\">Matrimonial<\/a><\/div><header class=\"directorypress-listing-title\"><h2><a href=\"https:\/\/classiads.designinvento.net\/elementor\/classiads-ola\/listings\/finding-best-match\/\" title=\"Finding Best Match\" rel=\"nofollow\">Finding Best Match<i class=\"user-verification-tag verified dicode-material-icons dicode-material-icons-checkbox-marked-circle\"><\/i><\/a><\/h2><\/header><div id=\"fields-block-inline11077\" class=\"grid-fields-wrapper inline-fields clearfix\" data-id=\"11077\"><\/div><div class=\"grid-fields-wrapper block-fields clearfix\"><\/div><div class=\"grid-exerpt-field clearfix\"><\/div><\/div><div class=\"listing-bottom-metas clearfix\"><div class=\"price\"><div class=\"directorypress-field-item directorypress-field-id-9 directorypress-field-type-price\">\r\n\t<span class=\"field-label\">\r\n\t\t\t<\/span>\r\n\t<span class=\"field-content symbol-left\">\r\n\tOn Call\t<\/span>\r\n<\/div><\/div><div class=\"listing-ratting-icon-fields clearfix\"><div class=\"tooltip_fields clearfix\"><a id=\"11077\" href=\"void(0);\" class=\"add_to_favourites btn\" data-listingid=\"11077\" data-bs-toggle=\"tooltip\" title=\"Bookmark\" data-in_favourites_icon=\"dicode-material-icons dicode-material-icons-heart\" data-not_in_favourites_icon=\"dicode-material-icons dicode-material-icons-heart\"><span class=\"favourite-icon style2 unchecked dicode-material-icons dicode-material-icons-heart\"><\/span><\/a><div id=\"fields-block-inline-tooltip11077\" class=\"inline-tooltip-fields clearfix\" data-id=\"11077\"><div id=\"directorypress-6\" class=\"directorypress-field-item directorypress-field-type-text\">\r\n\t<span class=\"field-label inline-field-label\">\r\n\t\t\t<span class=\"directorypress-field-icon pacz-fic2-iphone\" data-bs-toggle=\"tooltip\" title=\"+&#57;&#50;3&#52;5&#54;78&#57;9\" data-placement=\"auto\"><\/span>\t<\/span>\r\n\t\t\t\t<\/div>\r\n<\/div><\/div><\/div><\/div><\/div><\/article><article id=\"post-11076\" class=\"row directorypress-listing clearfix  responsive-2col m-grid-item listing-post-style-14 listing-grid-item\" style=\"padding-left:5px;padding-right:5px; margin-bottom:10px;\"><div class=\"directorypress-listing-item-holder clearfix\"><figure class=\"directorypress-listing-figure\"><a class=\"listing-thumbnail\" href=\"https:\/\/classiads.designinvento.net\/elementor\/classiads-ola\/listings\/fancy-lamps-for-sale\/\"><img loading=\"lazy\" decoding=\"async\" alt=\"Fancy Lamps For Sale\" src=\"https:\/\/classiads.designinvento.net\/elementor\/classiads-ola\/wp-content\/uploads\/bfi_thumb\/6-1-rj5lmyu5578opdn78y56ydlfk8z3n8fucwh9uchk30.jpg\" width=\"290\" height=\"190\" \/><\/a><div class=\"listing-grid-buttons clearfix\"><\/div><div class=\"listing-rating grid-rating\"><span class=\"rating-numbers\">4.0<\/span><span class=\"rating-stars\">\t<a href=\"#comments\" class=\"single-rating review_rate display-only\" data-dirrater=\"4.00\" itemprop=\"aggregateRating\" itemscope=\"\" itemtype=\"http:\/\/schema.org\/AggregateRating\">\r\n\t\t<span class=\"rating-value\">(<span itemprop=\"reviewCount\">1<\/span>)<\/span>\r\n\t\t<meta itemprop=\"ratingValue\" content = \"4.00\">\r\n\t<\/a>\r\n\t<\/span><\/div><\/figure><div class=\"clearfix directorypress-listing-text-content-wrap\"><div class=\"listng-author-img\"><a href=\"https:\/\/classiads.designinvento.net\/elementor\/classiads-ola\/author\/designinvento\/?profile=true\"><img class='directorypress-user-avatar' src='https:\/\/classiads.designinvento.net\/elementor\/classiads-ola\/wp-content\/uploads\/bfi_thumb\/img-02-768x693-1-rj5lmyu2cc1ggk7wfitymi37k7qk030vf9f7q2wx20.jpg' alt='author' \/><span class=\"author-in-active\"><\/span><\/a><\/div><div class=\"cat-wrapper\"><a class=\"listing-cat\" href=\"https:\/\/classiads.designinvento.net\/elementor\/classiads-ola\/listings\/business-category\/furniture\/\" rel=\"tag\">Furniture<\/a><\/div><header class=\"directorypress-listing-title\"><h2><a href=\"https:\/\/classiads.designinvento.net\/elementor\/classiads-ola\/listings\/fancy-lamps-for-sale\/\" title=\"Fancy Lamps For Sale\" rel=\"nofollow\">Fancy Lamps For Sale<i class=\"user-verification-tag verified dicode-material-icons dicode-material-icons-checkbox-marked-circle\"><\/i><\/a><\/h2><\/header><div id=\"fields-block-inline11076\" class=\"grid-fields-wrapper inline-fields clearfix\" data-id=\"11076\"><\/div><div class=\"grid-fields-wrapper block-fields clearfix\"><\/div><div class=\"grid-exerpt-field clearfix\"><\/div><\/div><div class=\"listing-bottom-metas clearfix\"><div class=\"price\"><div class=\"directorypress-field-item directorypress-field-id-9 directorypress-field-type-price\">\r\n\t<span class=\"field-label\">\r\n\t\t\t<\/span>\r\n\t<span class=\"field-content symbol-left\">\r\n\t<span class=\"currency-symbol\">$<\/span>5000 <span class=\"price-options\">Fixed<\/span>\t<\/span>\r\n<\/div><\/div><div class=\"listing-ratting-icon-fields clearfix\"><div class=\"tooltip_fields clearfix\"><a id=\"11076\" href=\"void(0);\" class=\"add_to_favourites btn\" data-listingid=\"11076\" data-bs-toggle=\"tooltip\" title=\"Bookmark\" data-in_favourites_icon=\"dicode-material-icons dicode-material-icons-heart\" data-not_in_favourites_icon=\"dicode-material-icons dicode-material-icons-heart\"><span class=\"favourite-icon style2 unchecked dicode-material-icons dicode-material-icons-heart\"><\/span><\/a><div id=\"fields-block-inline-tooltip11076\" class=\"inline-tooltip-fields clearfix\" data-id=\"11076\"><div id=\"directorypress-6\" class=\"directorypress-field-item directorypress-field-type-text\">\r\n\t<span class=\"field-label inline-field-label\">\r\n\t\t\t<span class=\"directorypress-field-icon pacz-fic2-iphone\" data-bs-toggle=\"tooltip\" title=\"+92&#51;45&#54;7&#56;9&#57;\" data-placement=\"auto\"><\/span>\t<\/span>\r\n\t\t\t\t<\/div>\r\n<\/div><\/div><\/div><\/div><\/div><\/article><article id=\"post-11075\" class=\"row directorypress-listing clearfix  responsive-2col m-grid-item listing-post-style-14 listing-grid-item\" style=\"padding-left:5px;padding-right:5px; margin-bottom:10px;\"><div class=\"directorypress-listing-item-holder clearfix\"><figure class=\"directorypress-listing-figure\"><a class=\"listing-thumbnail\" href=\"https:\/\/classiads.designinvento.net\/elementor\/classiads-ola\/listings\/double-bed-set\/\"><img loading=\"lazy\" decoding=\"async\" alt=\"Double Bed Set\" src=\"https:\/\/classiads.designinvento.net\/elementor\/classiads-ola\/wp-content\/uploads\/bfi_thumb\/bad-rj5lmyu5578opdn78y56ydlfk8z3n8fucwh9uchk30.jpg\" width=\"290\" height=\"190\" \/><\/a><div class=\"listing-grid-buttons clearfix\"><\/div><div class=\"listing-rating grid-rating\"><span class=\"rating-numbers\">5.0<\/span><span class=\"rating-stars\">\t<a href=\"#comments\" class=\"single-rating review_rate display-only\" data-dirrater=\"5.00\" itemprop=\"aggregateRating\" itemscope=\"\" itemtype=\"http:\/\/schema.org\/AggregateRating\">\r\n\t\t<span class=\"rating-value\">(<span itemprop=\"reviewCount\">1<\/span>)<\/span>\r\n\t\t<meta itemprop=\"ratingValue\" content = \"5.00\">\r\n\t<\/a>\r\n\t<\/span><\/div><\/figure><div class=\"clearfix directorypress-listing-text-content-wrap\"><div class=\"listng-author-img\"><a href=\"https:\/\/classiads.designinvento.net\/elementor\/classiads-ola\/author\/designinvento\/?profile=true\"><img class='directorypress-user-avatar' src='https:\/\/classiads.designinvento.net\/elementor\/classiads-ola\/wp-content\/uploads\/bfi_thumb\/img-02-768x693-1-rj5lmyu2cc1ggk7wfitymi37k7qk030vf9f7q2wx20.jpg' alt='author' \/><span class=\"author-in-active\"><\/span><\/a><\/div><div class=\"cat-wrapper\"><a class=\"listing-cat\" href=\"https:\/\/classiads.designinvento.net\/elementor\/classiads-ola\/listings\/business-category\/furniture\/\" rel=\"tag\">Furniture<\/a><span class=\"cat-seperator fas fa-angle-right\"><\/span><a class=\"listing-cat\" href=\"https:\/\/classiads.designinvento.net\/elementor\/classiads-ola\/listings\/business-category\/furniture\/beds\/\" rel=\"tag\">Beds<\/a><\/div><header class=\"directorypress-listing-title\"><h2><a href=\"https:\/\/classiads.designinvento.net\/elementor\/classiads-ola\/listings\/double-bed-set\/\" title=\"Double Bed Set\" rel=\"nofollow\">Double Bed Set<i class=\"user-verification-tag verified dicode-material-icons dicode-material-icons-checkbox-marked-circle\"><\/i><\/a><\/h2><\/header><div id=\"fields-block-inline11075\" class=\"grid-fields-wrapper inline-fields clearfix\" data-id=\"11075\"><\/div><div class=\"grid-fields-wrapper block-fields clearfix\"><\/div><div class=\"grid-exerpt-field clearfix\"><\/div><\/div><div class=\"listing-bottom-metas clearfix\"><div class=\"price\"><div class=\"directorypress-field-item directorypress-field-id-9 directorypress-field-type-price\">\r\n\t<span class=\"field-label\">\r\n\t\t\t<\/span>\r\n\t<span class=\"field-content symbol-left\">\r\n\t<span class=\"currency-symbol\">$<\/span>2200 <span class=\"price-options\">Fixed<\/span>\t<\/span>\r\n<\/div><\/div><div class=\"listing-ratting-icon-fields clearfix\"><div class=\"tooltip_fields clearfix\"><a id=\"11075\" href=\"void(0);\" class=\"add_to_favourites btn\" data-listingid=\"11075\" data-bs-toggle=\"tooltip\" title=\"Bookmark\" data-in_favourites_icon=\"dicode-material-icons dicode-material-icons-heart\" data-not_in_favourites_icon=\"dicode-material-icons dicode-material-icons-heart\"><span class=\"favourite-icon style2 unchecked dicode-material-icons dicode-material-icons-heart\"><\/span><\/a><div id=\"fields-block-inline-tooltip11075\" class=\"inline-tooltip-fields clearfix\" data-id=\"11075\"><div id=\"directorypress-6\" class=\"directorypress-field-item directorypress-field-type-text\">\r\n\t<span class=\"field-label inline-field-label\">\r\n\t\t\t<span class=\"directorypress-field-icon pacz-fic2-iphone\" data-bs-toggle=\"tooltip\" title=\"&#43;92&#51;&#52;&#53;&#54;&#55;&#56;&#57;9\" data-placement=\"auto\"><\/span>\t<\/span>\r\n\t\t\t\t<\/div>\r\n<\/div><\/div><\/div><\/div><\/div><\/article><article id=\"post-11074\" class=\"row directorypress-listing clearfix  responsive-2col m-grid-item listing-post-style-14 listing-grid-item\" style=\"padding-left:5px;padding-right:5px; margin-bottom:10px;\"><div class=\"directorypress-listing-item-holder clearfix\"><figure class=\"directorypress-listing-figure\"><a class=\"listing-thumbnail\" href=\"https:\/\/classiads.designinvento.net\/elementor\/classiads-ola\/listings\/computer-table-for-sale\/\"><img loading=\"lazy\" decoding=\"async\" alt=\"Computer Table For Sale\" src=\"https:\/\/classiads.designinvento.net\/elementor\/classiads-ola\/wp-content\/uploads\/bfi_thumb\/t1-1-rj5lmyu5578opdn78y56ydlfk8z3n8fucwh9uchk30.jpg\" width=\"290\" height=\"190\" \/><\/a><div class=\"listing-grid-buttons clearfix\"><\/div><div class=\"listing-rating grid-rating\"><span class=\"rating-numbers\">5.0<\/span><span class=\"rating-stars\">\t<a href=\"#comments\" class=\"single-rating review_rate display-only\" data-dirrater=\"5.00\" itemprop=\"aggregateRating\" itemscope=\"\" itemtype=\"http:\/\/schema.org\/AggregateRating\">\r\n\t\t<span class=\"rating-value\">(<span itemprop=\"reviewCount\">1<\/span>)<\/span>\r\n\t\t<meta itemprop=\"ratingValue\" content = \"5.00\">\r\n\t<\/a>\r\n\t<\/span><\/div><\/figure><div class=\"clearfix directorypress-listing-text-content-wrap\"><div class=\"listng-author-img\"><a href=\"https:\/\/classiads.designinvento.net\/elementor\/classiads-ola\/author\/designinvento\/?profile=true\"><img class='directorypress-user-avatar' src='https:\/\/classiads.designinvento.net\/elementor\/classiads-ola\/wp-content\/uploads\/bfi_thumb\/img-02-768x693-1-rj5lmyu2cc1ggk7wfitymi37k7qk030vf9f7q2wx20.jpg' alt='author' \/><span class=\"author-in-active\"><\/span><\/a><\/div><div class=\"cat-wrapper\"><a class=\"listing-cat\" href=\"https:\/\/classiads.designinvento.net\/elementor\/classiads-ola\/listings\/business-category\/furniture\/\" rel=\"tag\">Furniture<\/a><\/div><header class=\"directorypress-listing-title\"><h2><a href=\"https:\/\/classiads.designinvento.net\/elementor\/classiads-ola\/listings\/computer-table-for-sale\/\" title=\"Computer Table For Sale\" rel=\"nofollow\">Computer Table For S<i class=\"user-verification-tag verified dicode-material-icons dicode-material-icons-checkbox-marked-circle\"><\/i><\/a><\/h2><\/header><div id=\"fields-block-inline11074\" class=\"grid-fields-wrapper inline-fields clearfix\" data-id=\"11074\"><\/div><div class=\"grid-fields-wrapper block-fields clearfix\"><\/div><div class=\"grid-exerpt-field clearfix\"><\/div><\/div><div class=\"listing-bottom-metas clearfix\"><div class=\"price\"><div class=\"directorypress-field-item directorypress-field-id-9 directorypress-field-type-price\">\r\n\t<span class=\"field-label\">\r\n\t\t\t<\/span>\r\n\t<span class=\"field-content symbol-left\">\r\n\t<span class=\"currency-symbol\">$<\/span>6000 <span class=\"price-options\">Fixed<\/span>\t<\/span>\r\n<\/div><\/div><div class=\"listing-ratting-icon-fields clearfix\"><div class=\"tooltip_fields clearfix\"><a id=\"11074\" href=\"void(0);\" class=\"add_to_favourites btn\" data-listingid=\"11074\" data-bs-toggle=\"tooltip\" title=\"Bookmark\" data-in_favourites_icon=\"dicode-material-icons dicode-material-icons-heart\" data-not_in_favourites_icon=\"dicode-material-icons dicode-material-icons-heart\"><span class=\"favourite-icon style2 unchecked dicode-material-icons dicode-material-icons-heart\"><\/span><\/a><div id=\"fields-block-inline-tooltip11074\" class=\"inline-tooltip-fields clearfix\" data-id=\"11074\"><div id=\"directorypress-6\" class=\"directorypress-field-item directorypress-field-type-text\">\r\n\t<span class=\"field-label inline-field-label\">\r\n\t\t\t<span class=\"directorypress-field-icon pacz-fic2-iphone\" data-bs-toggle=\"tooltip\" title=\"&#43;&#57;&#50;3&#52;5&#54;&#55;8&#57;9\" data-placement=\"auto\"><\/span>\t<\/span>\r\n\t\t\t\t<\/div>\r\n<\/div><\/div><\/div><\/div><\/div><\/article><\/div><button class=\"btn btn-primary btn-lg btn-block directorypress-show-more-button directorypress-new-btn-4 \" data-handler-hash=\"364d8a9609cc614e952f48c42cb45b1c\">Load More<\/button><\/div><\/div><div class=\"directorypress-content-wrap\" id=\"directorypress-handler-364d8a9609cc614e952f48c42cb45b1c\" data-handler-hash=\"364d8a9609cc614e952f48c42cb45b1c\"><\/div><\/div><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-eac2312 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"eac2312\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-60c37c6\" data-id=\"60c37c6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8f7d8cb elementor-widget elementor-widget-spacer\" data-id=\"8f7d8cb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>filtersReal EstateVehiclesMobile PhonesFurnitureServicesElectronicsJobsFashionAnimalEducationBaby ToysTravelEventsHealthMatrimonialcanadachinaUnited KingdomAustraliaPakistanIndiaFranceKSAItalyNew ZealandTurkeyUSA WaterproofYes12No5StatusFor Sale0For Rent0Wanted0Seller typeAgency19Personal35BreedGerman Shepherd3Labrador Retriever0Golden Retriever0Bulldog0Beagle0French Bulldog0Poodle0Rottweiler0Yorkshire Terrier0Boxer0Siberian Husky0GenderMale7Female3Brand Name&#8211; Select Brand Name &#8211;AppleSamsungHuaweiQmobileNokiaSonyLGHTCOppoBlackBerrySony EricssonConditionUsed29Brand New15PurposeSell25Rent5Wanted3Model Year202372022320211202012019220180201772016420153201412013220120201102010120082Exterior ColorBeige0Black6Blue0Brown0Green0Grey0Orange0Pink0Red1Silver0White2Yellow3Career LevelIntern\/Student0Entry Level0Experienced Professional4Department Head0GM \/ CEO \/ Country Head \/ President0Job shiftInternship0Freelance0Contract0Part Time2Full Time2Positions Available10203240526070809010010+0Gender RequirementMale1Female3SpecialtiesBreast Surgery1Cardiology1Clinical Neurophysiology1Colorectal Surgery1Cosmetic Dermatology1Ear1Endocrinology1Mole checks and monitoring1Property Type&#8211; Select Property Type &#8211;HousePlotsCommercialcolorsBlack10Red17Blue2Brown3Green5White0Purple0Yellow5Gray7Mobile FeaturesTouchscreen33G \/4G [&hellip;]<\/p>\n","protected":false},"author":28,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-4","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/classiads.designinvento.net\/elementor\/classiads-ola\/wp-json\/wp\/v2\/pages\/4","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/classiads.designinvento.net\/elementor\/classiads-ola\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/classiads.designinvento.net\/elementor\/classiads-ola\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/classiads.designinvento.net\/elementor\/classiads-ola\/wp-json\/wp\/v2\/users\/28"}],"replies":[{"embeddable":true,"href":"https:\/\/classiads.designinvento.net\/elementor\/classiads-ola\/wp-json\/wp\/v2\/comments?post=4"}],"version-history":[{"count":0,"href":"https:\/\/classiads.designinvento.net\/elementor\/classiads-ola\/wp-json\/wp\/v2\/pages\/4\/revisions"}],"wp:attachment":[{"href":"https:\/\/classiads.designinvento.net\/elementor\/classiads-ola\/wp-json\/wp\/v2\/media?parent=4"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}